{"id":6230,"date":"2026-01-28T20:06:07","date_gmt":"2026-01-28T19:06:07","guid":{"rendered":"https:\/\/langhuus.ch\/blog\/?post_type=tribe_events&#038;p=6230"},"modified":"2026-01-29T14:18:14","modified_gmt":"2026-01-29T13:18:14","slug":"de-chly-prinz","status":"publish","type":"tribe_events","link":"https:\/\/langhuus.ch\/blog\/event\/de-chly-prinz\/","title":{"rendered":"De chly Prinz"},"content":{"rendered":"<p><b>DE CHLY PRINZ SPRICHT SCHWEIZERDEUTSCH<\/b><\/p>\n<p>K\u00fcrzlich ist in Zug ein ganz besonderer literarischer Stern aufgegangen: \u00abLe petit prince\u00bb, Antoine de Saint-Exup\u00e9rys weltber\u00fchmtes Werk, wurde auf Zugerdialekt \u00fcbersetzt.<\/p>\n<p>Die <b>Zuger Schriftstellerin und B\u00fchnenk\u00fcnstlerin Judith Stadlin<\/b> hat dem bekannten Klassiker von Antoine de Saint-Exup\u00e9ry eine neue Stimme verliehen \u2013 eine, die direkt ins Herz der Region trifft. Sie heisst DE CHLY PRINZ.<\/p>\n<p>Diese Geschichte fasziniert und sein Inhalt ist mit den archetypischen Figuren nach wie vor sehr aktuell. Die rundum poetische Geschichte ber\u00fchrt Kinder und Erwachsene mit ihrer ihrer anschaulichen Poesie und ihrer starken Symbolkraft.<br \/>\nAlle verstehen sie, alle k\u00f6nnen dabei ihre eigenen, vielf\u00e4ltigen Interpretationen spielen lassen.<\/p>\n<p>Jetzt ist die bekannte Autorin und Schauspielerin mit ihrer zugerdeutschen B\u00fchnenlesung DE CHLY PRINZ unterwegs.<\/p>\n<p>DE CHLY PRINZ ist eine <span class=\"s2\"><b>Hybrid-Veranstaltung<\/b><\/span> f\u00fcr Kinder, Jugendliche und Erwachsene.<br \/>\nBei ihrer B\u00fchnenlesung unterst\u00fctzt Stadlin das Geschehen mit feinen Requisiten, die die Geschichte noch anschaulicher zum Tragen bringen.<\/p>\n<p><strong>19.00 Bar<\/strong><br \/>\n<strong>20.00 Auff\u00fchrung<\/strong><br \/>\n<strong>Kollekte<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>DE CHLY PRINZ SPRICHT SCHWEIZERDEUTSCH K\u00fcrzlich ist in Zug ein ganz besonderer literarischer Stern aufgegangen: \u00abLe petit prince\u00bb, Antoine de Saint-Exup\u00e9rys weltber\u00fchmtes Werk, wurde auf Zugerdialekt \u00fcbersetzt. Die Zuger Schriftstellerin [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":6238,"comment_status":"open","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","_tribe_events_status":"","_tribe_events_status_reason":"","_tribe_events_is_hybrid":"","_tribe_events_is_virtual":"","_tribe_events_virtual_video_source":"","_tribe_events_virtual_embed_video":"","_tribe_events_virtual_linked_button_text":"","_tribe_events_virtual_linked_button":"","_tribe_events_virtual_show_embed_at":"","_tribe_events_virtual_show_embed_to":[],"_tribe_events_virtual_show_on_event":"","_tribe_events_virtual_show_on_views":"","_tribe_events_virtual_url":"","footnotes":""},"tags":[],"tribe_events_cat":[64,58],"class_list":["post-6230","tribe_events","type-tribe_events","status-publish","has-post-thumbnail","hentry","tribe_events_cat-kunst","tribe_events_cat-lesungen","cat_kunst","cat_lesungen"],"_links":{"self":[{"href":"https:\/\/langhuus.ch\/blog\/wp-json\/wp\/v2\/tribe_events\/6230","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/langhuus.ch\/blog\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/langhuus.ch\/blog\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/langhuus.ch\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/langhuus.ch\/blog\/wp-json\/wp\/v2\/comments?post=6230"}],"version-history":[{"count":4,"href":"https:\/\/langhuus.ch\/blog\/wp-json\/wp\/v2\/tribe_events\/6230\/revisions"}],"predecessor-version":[{"id":6236,"href":"https:\/\/langhuus.ch\/blog\/wp-json\/wp\/v2\/tribe_events\/6230\/revisions\/6236"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/langhuus.ch\/blog\/wp-json\/wp\/v2\/media\/6238"}],"wp:attachment":[{"href":"https:\/\/langhuus.ch\/blog\/wp-json\/wp\/v2\/media?parent=6230"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/langhuus.ch\/blog\/wp-json\/wp\/v2\/tags?post=6230"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/langhuus.ch\/blog\/wp-json\/wp\/v2\/tribe_events_cat?post=6230"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}