{"id":6070,"date":"2025-12-16T11:47:16","date_gmt":"2025-12-16T10:47:16","guid":{"rendered":"https:\/\/langhuus.ch\/blog\/?post_type=tribe_events&#038;p=6070"},"modified":"2026-01-21T14:11:38","modified_gmt":"2026-01-21T13:11:38","slug":"andrea-nia-2","status":"publish","type":"tribe_events","link":"https:\/\/langhuus.ch\/blog\/event\/andrea-nia-2\/","title":{"rendered":"Andrea Nia &#8211; Tanz-Workshop, Brunch und Farb- und Stil-Impulse"},"content":{"rendered":"<ul>\n<li>Nia, getanzte Lebensfreude, Bewegung choreografiert und frei zu Musik<\/li>\n<li>genussvoll fr\u00fchst\u00fccken und zusammen sein<\/li>\n<li>entdecke neue Farben und Stile die zu dir passen<\/li>\n<\/ul>\n<h4>Programm<\/h4>\n<p>09.00\u201310.15 Uhr\u00a0<strong>Nia mit Andrea<\/strong><br \/>\n10.30\u201311.30 Uhr\u00a0<strong>Brunch,<\/strong>\u00a0Fr\u00fchst\u00fcck vom Feinsten<br \/>\n11.30\u2013 ca. 13.30 Uhr\u00a0<strong>Styling-Inspirationen mit Martina<\/strong><\/p>\n<h4>Gastreferentin Martina M\u00e4rchy, Farb- und Stil-Coach<\/h4>\n<p>Entdecke, wie Farben, Formen und Materialien dich zum Strahlen bringen und deinen pers\u00f6nlichen Ausdruck lebendig machen.<br \/>\nErlebe, wie Kleidung Teil deiner Bewegung wird \u2013 leicht, freudig und authentisch.<br \/>\nHole dir inspirierende Impulse und verbinde dich in kleinen, erlebbaren \u00dcbungen mit deinem ganz eigenen Stil.<br \/>\n<a href=\"https:\/\/www.aufhuebschen.ch\/\">aufhuebschen.ch<\/a><\/p>\n<h5>Bist du dabei an diesem speziellen Sonntag Morgen, mit\u00a0<strong>tanzen, brunchen und \u00abstylen<\/strong>\u00bb?<\/h5>\n<p><strong>Mitnehmen:<\/strong>\u00a0Tanzkleider, etwas zum \u00dcberziehen ( Faserpelz) oder wechseln, Sch\u00fcrze, Heissleimpistole (falls du eine hast)<br \/>\n<strong>Kosten:<\/strong>\u00a0CHF 110 ( inkl. Nia, Fr\u00fchst\u00fcck und Beratung)<br \/>\n<strong>Ort:<\/strong>\u00a0Langhuus, Fabrikstrasse 9 in Cham, \u00d6V erreichbar, Parkpl\u00e4tze vor dem Haus oder in der Tiefgarage.<br \/>\n<strong>Anmeldung:\u00a0<\/strong>bis am 18. Januar 2025 (Durchf\u00fchrung ab 5 Personen)<\/p>\n<p><a href=\"mailto:andrea.sidler@datazug.ch\">Jetzt per Email anmelden<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nia, getanzte Lebensfreude, Bewegung choreografiert und frei zu Musik genussvoll fr\u00fchst\u00fccken und zusammen sein entdecke neue Farben und Stile die zu dir passen Programm 09.00\u201310.15 Uhr\u00a0Nia mit Andrea 10.30\u201311.30 Uhr\u00a0Brunch,\u00a0Fr\u00fchst\u00fcck [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":5072,"comment_status":"open","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","_tribe_events_status":"canceled","_tribe_events_status_reason":"","_tribe_events_is_hybrid":"","_tribe_events_is_virtual":"","_tribe_events_virtual_video_source":"","_tribe_events_virtual_embed_video":"","_tribe_events_virtual_linked_button_text":"","_tribe_events_virtual_linked_button":"","_tribe_events_virtual_show_embed_at":"","_tribe_events_virtual_show_embed_to":[],"_tribe_events_virtual_show_on_event":"","_tribe_events_virtual_show_on_views":"","_tribe_events_virtual_url":"","footnotes":""},"tags":[],"tribe_events_cat":[178,197,63,139],"class_list":["post-6070","tribe_events","type-tribe_events","status-publish","has-post-thumbnail","hentry","tribe_events_cat-bewegung","tribe_events_cat-gesundheit","tribe_events_cat-tanzen","tribe_events_cat-workshop","cat_bewegung","cat_gesundheit","cat_tanzen","cat_workshop","tribe-events-status__list-event-canceled"],"_links":{"self":[{"href":"https:\/\/langhuus.ch\/blog\/wp-json\/wp\/v2\/tribe_events\/6070","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/langhuus.ch\/blog\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/langhuus.ch\/blog\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/langhuus.ch\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/langhuus.ch\/blog\/wp-json\/wp\/v2\/comments?post=6070"}],"version-history":[{"count":4,"href":"https:\/\/langhuus.ch\/blog\/wp-json\/wp\/v2\/tribe_events\/6070\/revisions"}],"predecessor-version":[{"id":6074,"href":"https:\/\/langhuus.ch\/blog\/wp-json\/wp\/v2\/tribe_events\/6070\/revisions\/6074"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/langhuus.ch\/blog\/wp-json\/wp\/v2\/media\/5072"}],"wp:attachment":[{"href":"https:\/\/langhuus.ch\/blog\/wp-json\/wp\/v2\/media?parent=6070"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/langhuus.ch\/blog\/wp-json\/wp\/v2\/tags?post=6070"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/langhuus.ch\/blog\/wp-json\/wp\/v2\/tribe_events_cat?post=6070"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}