{"id":10004819,"date":"2025-11-27T18:36:04","date_gmt":"2025-11-27T17:36:04","guid":{"rendered":"https:\/\/langhuus.ch\/blog\/?post_type=tribe_events&#038;p=6023"},"modified":"2026-08-24T11:30:27","modified_gmt":"2026-08-24T09:30:27","slug":"shaya-white-circle-8","status":"publish","type":"tribe_events","link":"https:\/\/langhuus.ch\/blog\/event\/shaya-white-circle-8\/2026-10-28\/","title":{"rendered":"Raum zum Sein"},"content":{"rendered":"<p>Shaya ist langj\u00e4hrige Therapeutin und arbeitet in Cham als Naturheilpraktikerin in eigener Praxis. Sie bietet regelm\u00e4ssig Themenabende hier im Langhuus an. Dabei geht es vor allem darum, sich selbst zu begegnen, innezuhalten und bewusst Zeit f\u00fcr sich zu nehmen.<\/p>\n<p>Vielen lieben Dank f\u00fcrs Anpassen.<\/p>\n<p>Herzliche Gr\u00fcsse<br \/>\nShaya\ud83e\udd8b<\/p>\n<p>Teilnehmer Info:<br \/>\nMitnehmen: Matte, Decke, Kissen, Schreibzeug<br \/>\nKosten : Chf 40.- in Bar<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Shaya ist langj\u00e4hrige Therapeutin und arbeitet in Cham als Naturheilpraktikerin in eigener Praxis. Sie bietet regelm\u00e4ssig Themenabende hier im Langhuus an. Dabei geht es vor allem darum, sich selbst zu [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":4397,"comment_status":"open","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","_tribe_events_status":"","_tribe_events_status_reason":"","_tribe_events_is_hybrid":"","_tribe_events_is_virtual":"","_tribe_events_virtual_video_source":"","_tribe_events_virtual_embed_video":"","_tribe_events_virtual_linked_button_text":"","_tribe_events_virtual_linked_button":"","_tribe_events_virtual_show_embed_at":"","_tribe_events_virtual_show_embed_to":[],"_tribe_events_virtual_show_on_event":"","_tribe_events_virtual_show_on_views":"","_tribe_events_virtual_url":"","footnotes":""},"tags":[],"tribe_events_cat":[60,195,139],"class_list":["post-10004819","tribe_events","type-tribe_events","status-publish","has-post-thumbnail","hentry","tribe_events_cat-gesellschaft-gemeinschaft","tribe_events_cat-musik","tribe_events_cat-workshop","cat_gesellschaft-gemeinschaft","cat_musik","cat_workshop","tribe-recurring-event","tribe-recurring-event-parent"],"_links":{"self":[{"href":"https:\/\/langhuus.ch\/blog\/wp-json\/wp\/v2\/tribe_events\/10004819","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/langhuus.ch\/blog\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/langhuus.ch\/blog\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/langhuus.ch\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/langhuus.ch\/blog\/wp-json\/wp\/v2\/comments?post=10004819"}],"version-history":[{"count":0,"href":"https:\/\/langhuus.ch\/blog\/wp-json\/wp\/v2\/tribe_events\/10004819\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/langhuus.ch\/blog\/wp-json\/wp\/v2\/media\/4397"}],"wp:attachment":[{"href":"https:\/\/langhuus.ch\/blog\/wp-json\/wp\/v2\/media?parent=10004819"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/langhuus.ch\/blog\/wp-json\/wp\/v2\/tags?post=10004819"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/langhuus.ch\/blog\/wp-json\/wp\/v2\/tribe_events_cat?post=10004819"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}