{"id":10001812,"date":"2023-10-06T13:47:56","date_gmt":"2023-10-06T11:47:56","guid":{"rendered":"https:\/\/langhuus.ch\/blog\/?post_type=tribe_events&#038;p=3879"},"modified":"2024-03-01T09:45:25","modified_gmt":"2024-03-01T08:45:25","slug":"pinpong-2","status":"publish","type":"tribe_events","link":"https:\/\/langhuus.ch\/blog\/event\/pinpong-2\/2026-06-24\/","title":{"rendered":"PingPong"},"content":{"rendered":"<p>Jeden 2. und 4. Mittwoch im Monat flitzt der weisse Ball \u00fcber den PingPong Tisch. Sei dabei.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Jeden 2. und 4. Mittwoch im Monat flitzt der weisse Ball \u00fcber den PingPong Tisch. Sei dabei.<\/p>\n","protected":false},"author":1,"featured_media":2690,"comment_status":"open","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","_tribe_events_status":"","_tribe_events_status_reason":"","_tribe_events_is_hybrid":"","_tribe_events_is_virtual":"","_tribe_events_virtual_video_source":"","_tribe_events_virtual_embed_video":"","_tribe_events_virtual_linked_button_text":"","_tribe_events_virtual_linked_button":"","_tribe_events_virtual_show_embed_at":"","_tribe_events_virtual_show_embed_to":[],"_tribe_events_virtual_show_on_event":"","_tribe_events_virtual_show_on_views":"","_tribe_events_virtual_url":"","footnotes":""},"tags":[],"tribe_events_cat":[61,148],"class_list":["post-10001812","tribe_events","type-tribe_events","status-publish","has-post-thumbnail","hentry","tribe_events_cat-spiele","tribe_events_cat-sport","cat_spiele","cat_sport","tribe-recurring-event","tribe-recurring-event-parent"],"_links":{"self":[{"href":"https:\/\/langhuus.ch\/blog\/wp-json\/wp\/v2\/tribe_events\/10001812","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/langhuus.ch\/blog\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/langhuus.ch\/blog\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/langhuus.ch\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/langhuus.ch\/blog\/wp-json\/wp\/v2\/comments?post=10001812"}],"version-history":[{"count":0,"href":"https:\/\/langhuus.ch\/blog\/wp-json\/wp\/v2\/tribe_events\/10001812\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/langhuus.ch\/blog\/wp-json\/wp\/v2\/media\/2690"}],"wp:attachment":[{"href":"https:\/\/langhuus.ch\/blog\/wp-json\/wp\/v2\/media?parent=10001812"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/langhuus.ch\/blog\/wp-json\/wp\/v2\/tags?post=10001812"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/langhuus.ch\/blog\/wp-json\/wp\/v2\/tribe_events_cat?post=10001812"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}