{"id":1484,"date":"2021-12-09T19:58:08","date_gmt":"2021-12-09T18:58:08","guid":{"rendered":"https:\/\/langhuus.ch\/blog\/?p=1484"},"modified":"2021-12-09T20:48:36","modified_gmt":"2021-12-09T19:48:36","slug":"die-uhr-tickt-wieder-ab-dem-12-12-um-1212","status":"publish","type":"post","link":"https:\/\/langhuus.ch\/blog\/2021\/12\/09\/die-uhr-tickt-wieder-ab-dem-12-12-um-1212\/","title":{"rendered":"Die Uhr tickt wieder ab dem 12.12 um 12:12"},"content":{"rendered":"\n<p>Die Ingenieure:innen, Bastler:innen und K\u00fcnstler:innen haben der Uhr neues Leben eingehaucht. <\/p>\n\n\n\n<p>Sie tickt wieder &#8211; aber neuartig!<\/p>\n\n\n\n<p>Per Upload kannst auch du der Uhr neue T\u00e4nze beibringen &#8230;<\/p>\n\n\n\n<p>Willst du schon \u00fcben? <a rel=\"noreferrer noopener\" href=\"https:\/\/pantoffel.ch\/uhr\" target=\"_blank\">Hier findest du unseren Uhren-Tanz-Simulator<\/a><\/p>\n\n\n\n<p>Die Vernissage findet am 12.12 um 12:12 im <a rel=\"noreferrer noopener\" href=\"https:\/\/pantoffel.ch\" target=\"_blank\">Pantoffel Off Space<\/a> beim Sportplatz R\u00f6hliberg in Cham statt.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Ingenieure:innen, Bastler:innen und K\u00fcnstler:innen haben der Uhr neues Leben eingehaucht. Sie tickt wieder &#8211; aber neuartig! Per Upload kannst auch du der Uhr neue T\u00e4nze beibringen &#8230; Willst du [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1485,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"off","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-1484","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/langhuus.ch\/blog\/wp-json\/wp\/v2\/posts\/1484","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/langhuus.ch\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/langhuus.ch\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/langhuus.ch\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/langhuus.ch\/blog\/wp-json\/wp\/v2\/comments?post=1484"}],"version-history":[{"count":5,"href":"https:\/\/langhuus.ch\/blog\/wp-json\/wp\/v2\/posts\/1484\/revisions"}],"predecessor-version":[{"id":1491,"href":"https:\/\/langhuus.ch\/blog\/wp-json\/wp\/v2\/posts\/1484\/revisions\/1491"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/langhuus.ch\/blog\/wp-json\/wp\/v2\/media\/1485"}],"wp:attachment":[{"href":"https:\/\/langhuus.ch\/blog\/wp-json\/wp\/v2\/media?parent=1484"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/langhuus.ch\/blog\/wp-json\/wp\/v2\/categories?post=1484"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/langhuus.ch\/blog\/wp-json\/wp\/v2\/tags?post=1484"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}